{"id":21758,"date":"2023-09-06T15:50:14","date_gmt":"2023-09-06T13:50:14","guid":{"rendered":"https:\/\/www.dudelange.lu\/?post_type=evenement&#038;p=21758"},"modified":"2023-09-06T16:10:38","modified_gmt":"2023-09-06T14:10:38","slug":"soiree-dinformation-misez-sur-le-soleil-une-source-denergie-renouvelable","status":"publish","type":"evenement","link":"https:\/\/www.dudelange.lu\/index.php\/evenement\/soiree-dinformation-misez-sur-le-soleil-une-source-denergie-renouvelable\/","title":{"rendered":"Soir\u00e9e d&rsquo;information &#8211; Misez sur le soleil : une source d\u2019\u00e9nergie renouvelable !"},"content":{"rendered":"<p>Vous souhaitez vous informer sur l\u2019installation de panneaux solaires ? Sur les surfaces sur lesquelles vous pourriez les poser ? Sur les tarifs d\u2019injection et les primes \u00e9tatiques et les possibilit\u00e9s d\u2019autoconsommer votre production ?<br \/>\nVotre conseiller Klima-Agence r\u00e9pond \u00e0 vos questions !<\/p>\n<p>O\u00f9 ? Festsall Fran\u00e7ois Blouet \u2013 40, Grand-Rue \u2013 L-3394 Roeser<br \/>\nLangue : luxembourgeois<br \/>\nEntr\u00e9e libre<\/p>\n<p>Cette soir\u00e9e d&rsquo;information, organis\u00e9e \u00e0 l&rsquo;initiative de la Klima-Agence et du Step, est soutenue entre autres par la Ville de Dudelange.<\/p>\n<p>&#8212;-<\/p>\n<p>Setzen Sie auf die Sonne, eine nachhaltige und erneuerbare Energiequelle!<\/p>\n<p>Sie m\u00f6chten sich \u00fcber Photovoltaik-Anlagen informieren? Welche Fl\u00e4chen eignen sich f\u00fcr die Installation einer Anlage? Welche Einspeisetarife und staatliche Pr\u00e4mien gibt es? Oder m\u00f6chten Sie Ihren produzierten Strom selbst verbrauchen?<br \/>\nIhr Klima-Agence-Berater beantwortet Ihre Fragen!<\/p>\n<p>Wo? Festsall Fran\u00e7ois Blouet\u2013 40, Grand-Rue \u2013 L-3394 Roeser<br \/>\nSprache: Luxemburgisch<br \/>\nFreier Eintritt<\/p>\n<p>Dieser Informationsabend, der auf Initiative der Klima-Agence und des Step stattfindet, wird von u.a. der Stadt D\u00fcdelingen unterst\u00fctzt.<\/p>\n<p>[PDF] <span style=\"text-decoration: underline;\"><span style=\"color: #ef4030;\"><a style=\"color: #ef4030; text-decoration: underline;\" href=\"https:\/\/sadudelangedata.blob.core.windows.net\/files\/2023\/09\/2023085039_Klima-Agence_Infopoint-STEP-TO_141023_afficheA3.pdf\" target=\"_blank\" rel=\"noopener\">Flyer<\/a><\/span><\/span><\/p>\n","protected":false},"featured_media":21760,"template":"","categories":[],"class_list":["post-21758","evenement","type-evenement","status-publish","has-post-thumbnail","hentry"],"date_from":"2023-10-24 19:00:00","date_to":"2023-10-24 21:00:00","jour_entier":"0","date_debut_affichage":"0000-00-00 00:00:00","date_fin_affichage":"0000-00-00 00:00:00","description_ecran":"","organisateur":"","place_name":"Commune de Roeser","address":"","website":"https:\/\/www.klima-agence.lu","prix":[],"place_hotel_de_ville":"0","gare_dudelange_ville":"0","lycee_nic_biever":"0","preview":"0","visuel_prepare":false,"latitude":"","longitude":"","ordre_affichage_ecran":"0","import_id":"","export_id":"","picture_url":"https:\/\/sadudelangedata.blob.core.windows.net\/files\/2023\/09\/2022044682_klima-agence_images-web-Infopoint_1200x600_linkedin-10.jpg","publishpress_future_action":{"enabled":false,"date":"2026-05-20 17:21:51","action":"change-status","newStatus":"trash","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.dudelange.lu\/index.php\/wp-json\/wp\/v2\/evenement\/21758","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dudelange.lu\/index.php\/wp-json\/wp\/v2\/evenement"}],"about":[{"href":"https:\/\/www.dudelange.lu\/index.php\/wp-json\/wp\/v2\/types\/evenement"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dudelange.lu\/index.php\/wp-json\/wp\/v2\/media\/21760"}],"wp:attachment":[{"href":"https:\/\/www.dudelange.lu\/index.php\/wp-json\/wp\/v2\/media?parent=21758"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dudelange.lu\/index.php\/wp-json\/wp\/v2\/categories?post=21758"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}