{"id":26780,"date":"2025-02-13T11:24:30","date_gmt":"2025-02-13T10:24:30","guid":{"rendered":"https:\/\/www.dudelange.lu\/?post_type=evenement&#038;p=26780"},"modified":"2026-06-21T14:33:35","modified_gmt":"2026-06-21T12:33:35","slug":"veille-fete-nationale-2026","status":"publish","type":"evenement","link":"https:\/\/www.dudelange.lu\/index.php\/evenement\/veille-fete-nationale-2026\/","title":{"rendered":"Veille de la F\u00eate nationale"},"content":{"rendered":"<p>La Ville de Dudelange a le plaisir de vous pr\u00e9senter le programme des festivit\u00e9s qui auront lieu sur la place de l\u2019H\u00f4tel de Ville \u00e0 la veille de la F\u00eate nationale. Stands de restauration sur place.<\/p>\n<ul>\n<li>19:15 Rassemblement des autorit\u00e9s et associations au Parc \u00c9mile Mayrisch<\/li>\n<li>19:30 D\u00e9part du cort\u00e8ge<\/li>\n<li>20:00\n<ul>\n<li>Allocution du bourgmestre<\/li>\n<li>Heemecht et hymne europ\u00e9en interpr\u00e9t\u00e9s par l\u2019Harmonie Municipale<br \/>\net l\u2019Harmonie Forge du Sud<\/li>\n<li>Soft drinks et bi\u00e8re offerts par la Ville de Dudelange pendant une demi-heure<\/li>\n<li>Top Fanfare Marching Band<\/li>\n<\/ul>\n<\/li>\n<li>21:00 Brass Machine <em>Rock\/Pop\/Soul Coverband<\/em><\/li>\n<li>DJ Ben Leo<\/li>\n<li>23:15\u00a0 Spectacle \u00ab\u00a0Palais des lumi\u00e8res\u00a0\u00bb<\/li>\n<li>DJ Ben Leo<\/li>\n<\/ul>\n<hr \/>\n<p>Die Stadt D\u00fcdelingen freut sich Ihnen das\u00a0 Programm der Festlichkeiten vorzustellen,\u00a0 welche auf dem Rathausplatz am Vorabend des Nationalfeiertages stattfinden werden. Restaurationsst\u00e4nde vor Ort.<\/p>\n<ul>\n<li>19:15 Zusammenkunft der Beh\u00f6rden und Vereine im \u00c9mile Mayrisch Park<\/li>\n<li>19:30 Start des Umzugs<\/li>\n<li>20:00\n<ul>\n<li>Ansprache des B\u00fcrgermeisters<\/li>\n<li>Heemecht und Europahymne vorgetragen von der Harmonie Municipale<br \/>\nund der Harmonie Forge du Sud<\/li>\n<li>Die Stadt D\u00fcdelingen bietet w\u00e4hrend einer halben Stunde kostenlose Softrinks und Bier an<\/li>\n<li>Top Fanfare Marching Band<\/li>\n<\/ul>\n<\/li>\n<li>21:00 Brass Machine <em>Rock\/Pop\/Soul Coverband<\/em><\/li>\n<li>DJ Ben Leo<\/li>\n<li>23:15\u00a0 Lichtspektakel \u00ab\u00a0Palast der Lichter\u00a0\u00bb<\/li>\n<li>DJ Ben Leo<\/li>\n<\/ul>\n<hr \/>\n<p><strong>Acc\u00e8s\/Urees<\/strong><\/p>\n<ul>\n<li>Bus 5, 8, 9, 10, 631, 651, DudBus1 (Champs-Vall\u00e9e) &gt; Rue K. Marx, Place Fohrmann, Route de Thionville<\/li>\n<li>Train\/Zug 60a &gt; Dudelange-Centre<\/li>\n<li>V\u00ebl\u2019Ok &gt; Place de l\u2019H\u00f4tel de Ville<\/li>\n<li>Infos :\u00a0<a title=\"Www.mobiliteit.lu\" href=\"http:\/\/www.mobiliteit.lu\/\" target=\"_blank\" rel=\"noopener\">www.mobiliteit.lu<\/a>\u00a0\/\u00a0<a title=\"Www.velok.lu\" href=\"http:\/\/www.velok.lu\/\" target=\"_blank\" rel=\"noopener\">www.velok.lu<\/a><\/li>\n<\/ul>\n","protected":false},"featured_media":17106,"template":["Evenement"],"categories":[],"class_list":["post-26780","evenement","type-evenement","status-publish","has-post-thumbnail","hentry"],"date_from":"2026-06-22 19:15:00","date_to":"2026-06-22 00:00:00","jour_entier":"1","date_debut_affichage":"2026-06-05 07:00:00","date_fin_affichage":"2026-06-22 23:45:00","description_ecran":"","organisateur":"www.dudelange.lu > Agenda","place_name":"Pl. H\u00f4tel de Ville","address":"","website":"","prix":"0.00","place_hotel_de_ville":"1","gare_dudelange_ville":"1","lycee_nic_biever":"1","preview":"1","visuel_prepare":false,"latitude":"","longitude":"","ordre_affichage_ecran":"18","import_id":"","export_id":"veille-fete-nationale","picture_url":"https:\/\/sadudelangedata.blob.core.windows.net\/files\/2022\/05\/Firowend-NationalFeierdag.png","publishpress_future_action":{"enabled":false,"date":"2026-07-22 22:47:43","action":"change-status","newStatus":"trash","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.dudelange.lu\/index.php\/wp-json\/wp\/v2\/evenement\/26780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dudelange.lu\/index.php\/wp-json\/wp\/v2\/evenement"}],"about":[{"href":"https:\/\/www.dudelange.lu\/index.php\/wp-json\/wp\/v2\/types\/evenement"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dudelange.lu\/index.php\/wp-json\/wp\/v2\/media\/17106"}],"wp:attachment":[{"href":"https:\/\/www.dudelange.lu\/index.php\/wp-json\/wp\/v2\/media?parent=26780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dudelange.lu\/index.php\/wp-json\/wp\/v2\/categories?post=26780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}